{"id":1139,"count":0,"description":"","link":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/","name":"Veredelte","slug":"veredelte","taxonomy":"brands","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veredelte-Archiv - Hishtil Catalogue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veredelte-Archiv - Hishtil Catalogue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/\" \/>\n<meta property=\"og:site_name\" content=\"Hishtil Catalogue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/brands\\\/veredelte\\\/\",\"url\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/brands\\\/veredelte\\\/\",\"name\":\"Veredelte-Archiv - Hishtil Catalogue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/brands\\\/veredelte\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/brands\\\/veredelte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veredelte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/\",\"name\":\"Hishtil Catalogue\",\"description\":\"A leading plant - Nursery Company\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catalogue.hishtil.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veredelte-Archiv - Hishtil Catalogue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/","og_locale":"de_DE","og_type":"article","og_title":"Veredelte-Archiv - Hishtil Catalogue","og_url":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/","og_site_name":"Hishtil Catalogue","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/","url":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/","name":"Veredelte-Archiv - Hishtil Catalogue","isPartOf":{"@id":"https:\/\/catalogue.hishtil.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/catalogue.hishtil.com\/de\/brands\/veredelte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/catalogue.hishtil.com\/de\/"},{"@type":"ListItem","position":2,"name":"Veredelte"}]},{"@type":"WebSite","@id":"https:\/\/catalogue.hishtil.com\/de\/#website","url":"https:\/\/catalogue.hishtil.com\/de\/","name":"Hishtil Catalogue","description":"A leading plant - Nursery Company","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catalogue.hishtil.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/catalogue.hishtil.com\/de\/wp-json\/wp\/v2\/brands\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catalogue.hishtil.com\/de\/wp-json\/wp\/v2\/brands"}],"about":[{"href":"https:\/\/catalogue.hishtil.com\/de\/wp-json\/wp\/v2\/taxonomies\/brands"}],"wp:post_type":[{"href":"https:\/\/catalogue.hishtil.com\/de\/wp-json\/wp\/v2\/product?brands=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}